{"id":744,"count":4,"description":"","link":"https:\/\/goiasemtempo.com.br\/home\/tag\/acoes-saude-publica\/","name":"A\u00e7\u00f5es sa\u00fade p\u00fablica","slug":"acoes-saude-publica","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts?tags=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}