{"id":72911,"date":"2023-12-28T14:49:04","date_gmt":"2023-12-28T14:49:04","guid":{"rendered":"https:\/\/goiasemtempo.com.br\/home\/?p=72911"},"modified":"2023-12-28T14:49:04","modified_gmt":"2023-12-28T14:49:04","slug":"mulher-furta-mochila-com-r-45-mil-em-goiania","status":"publish","type":"post","link":"https:\/\/goiasemtempo.com.br\/home\/mulher-furta-mochila-com-r-45-mil-em-goiania\/","title":{"rendered":"Mulher furta mochila com R$ 45 mil em Goi\u00e2nia"},"content":{"rendered":"<p>Uma mulher, de 48 anos, foi presa ap\u00f3s furtar uma mochila com R$ 45 mil dentro. O caso ocorreu na quarta-feira (27), no Jardim Curitiba 2, em\u00a0<a href=\"https:\/\/www.maisgoias.com.br\/tag\/goiania\" target=\"_blank\" rel=\"noreferrer noopener\">Goi\u00e2nia<\/a>.<\/p>\n<p>Imagens de c\u00e2mera de monitoramento mostram o momento em que a mulher pega a mochila, que estava na entrada de uma distribuidora de bebidas, e sai.<\/p>\n<p>A v\u00edtima, que \u00e9 propriet\u00e1ria da distribuidora, explicou \u00e0\u00a0<a href=\"https:\/\/www.pm.go.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Militar (PM)<\/a>\u00a0que estava em uma videochamada com um amigo e acabou tirando a mochila, pois estava pesada, para mostrar o estoque da loja. Assim, acabou se esquecendo do objeto deixado na porta da distribuidora,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma mulher, de 48 anos, foi presa ap\u00f3s furtar uma mochila com R$ 45 mil dentro. O caso ocorreu na quarta-feira (27), no Jardim Curitiba 2, em\u00a0Goi\u00e2nia. Imagens de c\u00e2mera de monitoramento mostram o momento em que a mulher pega a mochila, que estava na entrada de uma distribuidora de bebidas, e sai. A v\u00edtima, &hellip;<\/p>\n","protected":false},"author":3,"featured_media":72912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-72911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/72911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/comments?post=72911"}],"version-history":[{"count":1,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/72911\/revisions"}],"predecessor-version":[{"id":72913,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/72911\/revisions\/72913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media\/72912"}],"wp:attachment":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media?parent=72911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/categories?post=72911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags?post=72911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}