{"id":50798,"date":"2019-09-25T00:06:48","date_gmt":"2019-09-25T00:06:48","guid":{"rendered":"http:\/\/goiasemtempo.com.br\/home\/?p=50798"},"modified":"2019-09-25T00:06:48","modified_gmt":"2019-09-25T00:06:48","slug":"em-discurso-na-onu-bolsonaro-destaca-riqueza-da-amazonia","status":"publish","type":"post","link":"https:\/\/goiasemtempo.com.br\/home\/em-discurso-na-onu-bolsonaro-destaca-riqueza-da-amazonia\/","title":{"rendered":"Em discurso na ONU, Bolsonaro destaca riqueza da Amaz\u00f4nia"},"content":{"rendered":"<p>O presidente Jair Bolsonaro disse\u00a0hoje\u00a0(24) que a Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) n\u00e3o pode aceitar a volta do colonialismo e defendeu a soberania brasileira na Amaz\u00f4nia. Durante\u00a0discurso na abertura da 74\u00aa Assembleia Geral da ONU, em Nova York, nos Estados Unidos, Bolsonaro reafirmou o compromisso do pa\u00eds com a preserva\u00e7\u00e3o do meio ambiente e com o desenvolvimento sustent\u00e1vel da regi\u00e3o.<\/p>\n<p>\u201cO Brasil \u00e9 um dos pa\u00edses mais ricos em biodiversidade e riquezas minerais, nossa Amaz\u00f4nia \u00e9 maior que toda Europa Ocidental e permanece praticamente intocada, prova de que somos um dos pa\u00edses que mais protege o meio ambiente\u201d, disse ele aos chefes de Estado.<\/p>\n<p>Cerca de 14% do territ\u00f3rio brasileiro \u00e9 demarcado como terras ind\u00edgenas e Bolsonaro destacou que n\u00e3o pretende demarcar novos territ\u00f3rios.\u00a0&#8220;Quero deixar claro: o Brasil n\u00e3o vai aumentar para 20% sua \u00e1rea j\u00e1 demarcada como terra ind\u00edgena, como alguns chefes de Estados gostariam que acontecesse&#8221;, afirmou.\u00a0\u201cO \u00edndio n\u00e3o quer ser latifundi\u00e1rio pobre em cima de terras ricas. Especialmente das terras mais ricas do mundo. \u00c9 o caso das reservas Ianom\u00e2mi e Raposa Serra do Sol. Nessas reservas, existe grande abund\u00e2ncia de ouro, diamante, ur\u00e2nio, ni\u00f3bio e terras raras, entre outros\u201d, disse, destacando que o Brasil usa 8% de seu territ\u00f3rio para produ\u00e7\u00e3o de alimentos.<\/p>\n<p>O presidente brasileiro defendeu uma pol\u00edtica de toler\u00e2ncia zero com a criminalidade, incluindo os crimes ambientais, e ressaltou que os inc\u00eandios que v\u00eam ocorrendo na Amaz\u00f4nia nos \u00faltimos meses s\u00e3o caracter\u00edsticos desta \u00e9poca do ano, de seca e ventos. Bolsonaro criticou a m\u00eddia internacional pela repercuss\u00e3o negativa que as queimadas tiveram pelo mundo e a possibilidade de os pa\u00edses aplicarem san\u00e7\u00f5es econ\u00f4micas ao Brasil.<\/p>\n<p>\u201c\u00c9 uma fal\u00e1cia dizer que a Amaz\u00f4nia \u00e9 patrim\u00f4nio da humanidade e um equ\u00edvoco, como atestam os cientistas, afirmar que a nossa floresta \u00e9 o pulm\u00e3o do mundo. Valendo-se dessas fal\u00e1cias, um ou outro pa\u00eds, em vez de ajudar, embarcou nas mentiras da m\u00eddia e se portou de forma desrespeitosa, com esp\u00edrito colonialista. Questionaram aquilo que nos \u00e9 mais sagrado: a nossa soberania!\u201d, disse.<\/p>\n<p>Bolsonaro leu uma carta que, segundo ele, foi encaminhada aos chefes de Estado por um grupo de agricultores ind\u00edgenas do Brasil, formado por 52 etnias que habitam uma \u00e1rea de mais de 30 milh\u00f5es de hectares no territ\u00f3rio brasileiro. Na carta, eles apoiam a representa\u00e7\u00e3o da ind\u00edgena Ysani Kalapalo, moradora de uma aldeia no Parque Ind\u00edgena do Xingu, em\u00a0Mato Grosso, que integra a delega\u00e7\u00e3o brasileira na Assembleia Geral da ONU.<\/p>\n<p>\u201cExistem, no Brasil, 225 povos ind\u00edgenas, al\u00e9m de refer\u00eancias de 70 tribos vivendo em locais isolados. Cada povo ou tribo com seu cacique, sua cultura, suas tradi\u00e7\u00f5es, seus costumes e principalmente sua forma de ver o mundo. A vis\u00e3o de um l\u00edder ind\u00edgena n\u00e3o representa a de todos os \u00edndios brasileiros\u201d, disse Bolsonaro, argumentando que, muitas vezes, alguns desses l\u00edderes, como o cacique Raoni, s\u00e3o \u201cusados como pe\u00e7a de manobra por governos estrangeiros na sua guerra informacional para avan\u00e7ar seus interesses na Amaz\u00f4nia\u201d.<\/p>\n<p>Raoni Metuktire \u00e9 um l\u00edder ind\u00edgena brasileiro da etnia caiap\u00f3, conhecido internacionalmente por\u00a0sua atua\u00e7\u00e3o na\u00a0Amaz\u00f4nia. \u201cIsso demonstra que os que nos atacam n\u00e3o est\u00e3o preocupados com os \u00edndios, mas sim com as riquezas minerais e biodiversidade existentes nessa \u00e1rea\u201d, ressaltou. \u201cAcabou o monop\u00f3lio do Senhor Raoni. A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas teve papel fundamental na supera\u00e7\u00e3o do colonialismo e n\u00e3o pode aceitar que essa mentalidade regresse a estas salas e corredores, sob qualquer pretexto.&#8221;<\/p>\n<p>Bolsonaro disse ainda que qualquer iniciativa de ajuda ou apoio \u00e0 preserva\u00e7\u00e3o da Floresta Amaz\u00f4nica ou de outros biomas deve ser tratada com pleno respeito \u00e0 soberania brasileira e que busca parcerias para agregar valor de forma sustent\u00e1vel \u00e0s riquezas brasileiras. O presidente tamb\u00e9m recha\u00e7ou as tentativas de instrumentalizar a quest\u00e3o ambiental ou a pol\u00edtica indigenista em prol de interesses pol\u00edticos e econ\u00f4micos externos, \u201cem especial os disfar\u00e7ados de boas inten\u00e7\u00f5es\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro disse\u00a0hoje\u00a0(24) que a Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) n\u00e3o pode aceitar a volta do colonialismo e defendeu a soberania brasileira na Amaz\u00f4nia. Durante\u00a0discurso na abertura da 74\u00aa Assembleia Geral da ONU, em Nova York, nos Estados Unidos, Bolsonaro reafirmou o compromisso do pa\u00eds com a preserva\u00e7\u00e3o do meio ambiente e com &hellip;<\/p>\n","protected":false},"author":3,"featured_media":50799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-50798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete"],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/50798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/comments?post=50798"}],"version-history":[{"count":1,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/50798\/revisions"}],"predecessor-version":[{"id":50800,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/50798\/revisions\/50800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media\/50799"}],"wp:attachment":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media?parent=50798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/categories?post=50798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags?post=50798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}