{"id":47411,"date":"2019-04-29T23:03:27","date_gmt":"2019-04-29T23:03:27","guid":{"rendered":"http:\/\/goiasemtempo.com.br\/home\/?p=47411"},"modified":"2019-04-29T23:20:44","modified_gmt":"2019-04-29T23:20:44","slug":"multa-de-r-1-milhao-a-enel-goias-e-mantida-pela-agencia-nacional-de-energia","status":"publish","type":"post","link":"https:\/\/goiasemtempo.com.br\/home\/multa-de-r-1-milhao-a-enel-goias-e-mantida-pela-agencia-nacional-de-energia\/","title":{"rendered":"Multa de R$ 1 milh\u00e3o \u00e0 Enel Goi\u00e1s \u00e9 mantida pela Ag\u00eancia Nacional de Energia"},"content":{"rendered":"<p>A diretoria da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) n\u00e3o aceitou o recurso administrativo interposto pela Enel Distribui\u00e7\u00e3o Goi\u00e1s e manteve a penalidade relativa ao Auto de Infra\u00e7\u00e3o n\u00ba 0001\/2018, lavrado pela Ag\u00eancia Goiana de Regula\u00e7\u00e3o, Controle e Fiscaliza\u00e7\u00e3o de Servi\u00e7os P\u00fablicos (AGR).<\/p>\n<p>O valor da multa \u00e9 de aproximadamente R$ 1 milh\u00e3o e refere-se \u00e0 n\u00e3o conformidades nos \u00edndices NC.1, NC.2 e NC.3 do \u00f3rg\u00e3o regulador, os quais indicam falta de informa\u00e7\u00f5es adequadas sobre a opera\u00e7\u00e3o da distribuidora, o que causa dificuldades \u00e0s atividades de fiscaliza\u00e7\u00e3o, al\u00e9m da n\u00e3o apresenta\u00e7\u00e3o de dados adequados nas faturas de energia e aos consumidores dentro do prazo regulat\u00f3rio.<\/p>\n<p>Ag\u00eancia negou pedido da distribuidora, penalizada por n\u00e3o apresentar informa\u00e7\u00f5es adequadas sobre sua opera\u00e7\u00e3o e aos consumidores no prazo regulat\u00f3rio<\/p>\n<p>Fonte: Ag\u00eancia Canalenergia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diretoria da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) n\u00e3o aceitou o recurso administrativo interposto pela Enel Distribui\u00e7\u00e3o Goi\u00e1s e manteve a penalidade relativa ao Auto de Infra\u00e7\u00e3o n\u00ba 0001\/2018, lavrado pela Ag\u00eancia Goiana de Regula\u00e7\u00e3o, Controle e Fiscaliza\u00e7\u00e3o de Servi\u00e7os P\u00fablicos (AGR). O valor da multa \u00e9 de aproximadamente R$ 1 milh\u00e3o e refere-se &hellip;<\/p>\n","protected":false},"author":3,"featured_media":47412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-47411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete"],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/comments?post=47411"}],"version-history":[{"count":1,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47411\/revisions"}],"predecessor-version":[{"id":47413,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47411\/revisions\/47413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media\/47412"}],"wp:attachment":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media?parent=47411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/categories?post=47411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags?post=47411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}