{"id":47241,"date":"2019-04-23T00:30:16","date_gmt":"2019-04-23T00:30:16","guid":{"rendered":"http:\/\/goiasemtempo.com.br\/home\/?p=47241"},"modified":"2019-04-23T00:30:16","modified_gmt":"2019-04-23T00:30:16","slug":"urgente-stj-julga-recurso-de-lula-amanhaterca-feira","status":"publish","type":"post","link":"https:\/\/goiasemtempo.com.br\/home\/urgente-stj-julga-recurso-de-lula-amanhaterca-feira\/","title":{"rendered":"URGENTE: STJ JULGA RECURSO DE LULA AMANH\u00c3,TER\u00c7A-FEIRA"},"content":{"rendered":"<p>O Superior Tribunal de Justi\u00e7a acaba de anunciar que ser\u00e1 julgado amanh\u00e3, na Quinta Turma, o julgamento do recurso de Lula contra a condena\u00e7\u00e3o no caso do triplex.<\/p>\n<p>Em princ\u00edpio, participar\u00e3o do julgamento os ministros\u00a0Felix Fischer (relator),\u00a0Jorge Mussi,\u00a0Reynaldo Soares da Fonseca e\u00a0Ribeiro Dantas.<\/p>\n<p>O quinto integrante do colegiado,\u00a0Joel Ilan Paciornik, se declarou impedido e s\u00f3 ser\u00e1 substitu\u00eddo, por Antonio Saldanha Palheiro (da Sexta Turma) se houver empate no julgamento.<\/p>\n<p>Em resumo, a defesa de Lula pede absolvi\u00e7\u00e3o, sob alega\u00e7\u00e3o de falta de provas; anula\u00e7\u00e3o da condena\u00e7\u00e3o, por contestar a compet\u00eancia de Sergio Moro e da Justi\u00e7a Federal; ou redu\u00e7\u00e3o da pena de 12 anos e 9 meses, com a elimina\u00e7\u00e3o da condena\u00e7\u00e3o por lavagem de dinheiro.<\/p>\n<p>Com: Antagonista<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Superior Tribunal de Justi\u00e7a acaba de anunciar que ser\u00e1 julgado amanh\u00e3, na Quinta Turma, o julgamento do recurso de Lula contra a condena\u00e7\u00e3o no caso do triplex. Em princ\u00edpio, participar\u00e3o do julgamento os ministros\u00a0Felix Fischer (relator),\u00a0Jorge Mussi,\u00a0Reynaldo Soares da Fonseca e\u00a0Ribeiro Dantas. O quinto integrante do colegiado,\u00a0Joel Ilan Paciornik, se declarou impedido e s\u00f3 &hellip;<\/p>\n","protected":false},"author":3,"featured_media":47242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-47241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/comments?post=47241"}],"version-history":[{"count":1,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47241\/revisions"}],"predecessor-version":[{"id":47243,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/47241\/revisions\/47243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media\/47242"}],"wp:attachment":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media?parent=47241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/categories?post=47241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags?post=47241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}