{"id":34452,"date":"2018-04-03T16:37:23","date_gmt":"2018-04-03T16:37:23","guid":{"rendered":"https:\/\/goiasemtempo.com.br\/home\/?p=34452"},"modified":"2018-04-03T16:37:23","modified_gmt":"2018-04-03T16:37:23","slug":"rainha-elizabeth-participa-de-culto-de-pascoa-em-windsor","status":"publish","type":"post","link":"https:\/\/goiasemtempo.com.br\/home\/rainha-elizabeth-participa-de-culto-de-pascoa-em-windsor\/","title":{"rendered":"Rainha Elizabeth participa de culto de P\u00e1scoa em Windsor"},"content":{"rendered":"<p>LONDRES (Reuters) &#8211; A rainha Elizabeth compareceu, neste domingo, ao tradicional culto de P\u00e1scoa no Castelo de Windsor, juntando-se a outros membros da fam\u00edlia real na Capela de S\u00e3o Jorge, onde seu neto, o pr\u00edncipe Harry, deve se casar com Meghan Markle no pr\u00f3ximo m\u00eas.<\/p>\n<p>A monarca brit\u00e2nica, usando um chap\u00e9u e casaco roxo e um vestido floral, foi recebida na capela pelo decano de Windsor David Conner, que conduzir\u00e1 o culto de casamento no dia 19 de maio.<\/p>\n<p>Ela foi acompanhada por seu neto mais velho, o pr\u00edncipe William, e sua esposa Kate, que deve dar \u00e0 luz o terceiro filho do casal este m\u00eas, al\u00e9m de outros membros da fam\u00edlia real.<\/p>\n<p>O marido de 96 anos da rainha, o pr\u00edncipe Philip, n\u00e3o compareceu ao culto, assim como Harry e sua noiva.<\/p>\n<p>(Por Paul Sandle)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONDRES (Reuters) &#8211; A rainha Elizabeth compareceu, neste domingo, ao tradicional culto de P\u00e1scoa no Castelo de Windsor, juntando-se a outros membros da fam\u00edlia real na Capela de S\u00e3o Jorge, onde seu neto, o pr\u00edncipe Harry, deve se casar com Meghan Markle no pr\u00f3ximo m\u00eas. A monarca brit\u00e2nica, usando um chap\u00e9u e casaco roxo e &hellip;<\/p>\n","protected":false},"author":2,"featured_media":34080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-34452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/34452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/comments?post=34452"}],"version-history":[{"count":1,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/34452\/revisions"}],"predecessor-version":[{"id":34453,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/posts\/34452\/revisions\/34453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media\/34080"}],"wp:attachment":[{"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/media?parent=34452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/categories?post=34452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goiasemtempo.com.br\/home\/wp-json\/wp\/v2\/tags?post=34452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}